{"id":1398,"date":"2026-03-09T11:58:42","date_gmt":"2026-03-09T10:58:42","guid":{"rendered":"https:\/\/balzoscanno.com\/?post_type=percorso&#038;p=1398"},"modified":"2026-07-14T18:27:21","modified_gmt":"2026-07-14T16:27:21","slug":"sentiero-y9","status":"publish","type":"sentieri","link":"https:\/\/balzoscanno.com\/en\/sentieri\/sentiero-y9\/","title":{"rendered":"Sentiero Y9"},"content":{"rendered":"<p class=\"wp-block-paragraph\">Bellissimo sentiero che attraversa il Vallone di Ciaccariello fino ad arrivare alla zona di confine con il territorio di Pescasseroli. Lungo il percorso si possono ammirare splendide vedute sul Monte Genzana e sulle vette della Majella, compreso il Monte Amaro a 2783 metri.<\/p>","protected":false},"featured_media":1399,"template":"","meta":{"_acf_changed":true},"class_list":["post-1398","sentieri","type-sentieri","status-publish","has-post-thumbnail","hentry"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Sentiero Y9 - Balzo Scanno<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/balzoscanno.com\/en\/sentieri\/sentiero-y9\/\" \/>\n<meta property=\"og:locale\" content=\"en_GB\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Sentiero Y9 - Balzo Scanno\" \/>\n<meta property=\"og:description\" content=\"Bellissimo sentiero che attraversa il Vallone di Ciaccariello fino ad arrivare alla zona di confine con il territorio di Pescasseroli. Lungo il percorso si possono ammirare splendide vedute sul Monte Genzana e sulle vette della Majella, compreso il Monte Amaro a 2783 metri.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/balzoscanno.com\/en\/sentieri\/sentiero-y9\/\" \/>\n<meta property=\"og:site_name\" content=\"Balzo Scanno\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/profile.php?id=61572664227109\" \/>\n<meta property=\"article:modified_time\" content=\"2026-07-14T16:27:21+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/balzoscanno.com\/wp-content\/uploads\/2026\/03\/Cover-sentieri-copy-5.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1024\" \/>\n\t<meta property=\"og:image:height\" content=\"768\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Estimated reading time\" \/>\n\t<meta name=\"twitter:data1\" content=\"1 minute\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/balzoscanno.com\\\/sentieri\\\/sentiero-y9\\\/\",\"url\":\"https:\\\/\\\/balzoscanno.com\\\/sentieri\\\/sentiero-y9\\\/\",\"name\":\"Sentiero Y9 - Balzo Scanno\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/balzoscanno.com\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/balzoscanno.com\\\/sentieri\\\/sentiero-y9\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/balzoscanno.com\\\/sentieri\\\/sentiero-y9\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/balzoscanno.com\\\/wp-content\\\/uploads\\\/2026\\\/03\\\/Cover-sentieri-copy-5.jpg\",\"datePublished\":\"2026-03-09T10:58:42+00:00\",\"dateModified\":\"2026-07-14T16:27:21+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/balzoscanno.com\\\/sentieri\\\/sentiero-y9\\\/#breadcrumb\"},\"inLanguage\":\"en-GB\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/balzoscanno.com\\\/sentieri\\\/sentiero-y9\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-GB\",\"@id\":\"https:\\\/\\\/balzoscanno.com\\\/sentieri\\\/sentiero-y9\\\/#primaryimage\",\"url\":\"https:\\\/\\\/balzoscanno.com\\\/wp-content\\\/uploads\\\/2026\\\/03\\\/Cover-sentieri-copy-5.jpg\",\"contentUrl\":\"https:\\\/\\\/balzoscanno.com\\\/wp-content\\\/uploads\\\/2026\\\/03\\\/Cover-sentieri-copy-5.jpg\",\"width\":1024,\"height\":768,\"caption\":\"Stazzo di Ciaccariello\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/balzoscanno.com\\\/sentieri\\\/sentiero-y9\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/balzoscanno.com\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Sentieri\",\"item\":\"https:\\\/\\\/balzoscanno.com\\\/sentieri\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Sentiero Y9\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/balzoscanno.com\\\/#website\",\"url\":\"https:\\\/\\\/balzoscanno.com\\\/\",\"name\":\"Balzo Scanno\",\"description\":\"Balzo \u00e8 un progetto nato per rendere il territorio di Scanno pi\u00f9 accessibile a cittadini e turisti, fornendo informazioni e strumenti per viverlo al meglio.\",\"publisher\":{\"@id\":\"https:\\\/\\\/balzoscanno.com\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/balzoscanno.com\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-GB\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/balzoscanno.com\\\/#organization\",\"name\":\"Balzo Scanno\",\"url\":\"https:\\\/\\\/balzoscanno.com\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-GB\",\"@id\":\"https:\\\/\\\/balzoscanno.com\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/balzoscanno.com\\\/wp-content\\\/uploads\\\/2026\\\/03\\\/Balzo.png\",\"contentUrl\":\"https:\\\/\\\/balzoscanno.com\\\/wp-content\\\/uploads\\\/2026\\\/03\\\/Balzo.png\",\"width\":1601,\"height\":496,\"caption\":\"Balzo Scanno\"},\"image\":{\"@id\":\"https:\\\/\\\/balzoscanno.com\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/profile.php?id=61572664227109\",\"https:\\\/\\\/www.instagram.com\\\/balzo_scanno\\\/\",\"https:\\\/\\\/www.tiktok.com\\\/@balzo_scanno\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Sentiero Y9 - Balzo Scanno","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/balzoscanno.com\/en\/sentieri\/sentiero-y9\/","og_locale":"en_GB","og_type":"article","og_title":"Sentiero Y9 - Balzo Scanno","og_description":"Bellissimo sentiero che attraversa il Vallone di Ciaccariello fino ad arrivare alla zona di confine con il territorio di Pescasseroli. Lungo il percorso si possono ammirare splendide vedute sul Monte Genzana e sulle vette della Majella, compreso il Monte Amaro a 2783 metri.","og_url":"https:\/\/balzoscanno.com\/en\/sentieri\/sentiero-y9\/","og_site_name":"Balzo Scanno","article_publisher":"https:\/\/www.facebook.com\/profile.php?id=61572664227109","article_modified_time":"2026-07-14T16:27:21+00:00","og_image":[{"width":1024,"height":768,"url":"https:\/\/balzoscanno.com\/wp-content\/uploads\/2026\/03\/Cover-sentieri-copy-5.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_misc":{"Estimated reading time":"1 minute"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/balzoscanno.com\/sentieri\/sentiero-y9\/","url":"https:\/\/balzoscanno.com\/sentieri\/sentiero-y9\/","name":"Sentiero Y9 - Balzo Scanno","isPartOf":{"@id":"https:\/\/balzoscanno.com\/#website"},"primaryImageOfPage":{"@id":"https:\/\/balzoscanno.com\/sentieri\/sentiero-y9\/#primaryimage"},"image":{"@id":"https:\/\/balzoscanno.com\/sentieri\/sentiero-y9\/#primaryimage"},"thumbnailUrl":"https:\/\/balzoscanno.com\/wp-content\/uploads\/2026\/03\/Cover-sentieri-copy-5.jpg","datePublished":"2026-03-09T10:58:42+00:00","dateModified":"2026-07-14T16:27:21+00:00","breadcrumb":{"@id":"https:\/\/balzoscanno.com\/sentieri\/sentiero-y9\/#breadcrumb"},"inLanguage":"en-GB","potentialAction":[{"@type":"ReadAction","target":["https:\/\/balzoscanno.com\/sentieri\/sentiero-y9\/"]}]},{"@type":"ImageObject","inLanguage":"en-GB","@id":"https:\/\/balzoscanno.com\/sentieri\/sentiero-y9\/#primaryimage","url":"https:\/\/balzoscanno.com\/wp-content\/uploads\/2026\/03\/Cover-sentieri-copy-5.jpg","contentUrl":"https:\/\/balzoscanno.com\/wp-content\/uploads\/2026\/03\/Cover-sentieri-copy-5.jpg","width":1024,"height":768,"caption":"Stazzo di Ciaccariello"},{"@type":"BreadcrumbList","@id":"https:\/\/balzoscanno.com\/sentieri\/sentiero-y9\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/balzoscanno.com\/"},{"@type":"ListItem","position":2,"name":"Sentieri","item":"https:\/\/balzoscanno.com\/sentieri\/"},{"@type":"ListItem","position":3,"name":"Sentiero Y9"}]},{"@type":"WebSite","@id":"https:\/\/balzoscanno.com\/#website","url":"https:\/\/balzoscanno.com\/","name":"Balzo Scanno","description":"Balzo \u00e8 un progetto nato per rendere il territorio di Scanno pi\u00f9 accessibile a cittadini e turisti, fornendo informazioni e strumenti per viverlo al meglio.","publisher":{"@id":"https:\/\/balzoscanno.com\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/balzoscanno.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-GB"},{"@type":"Organization","@id":"https:\/\/balzoscanno.com\/#organization","name":"Balzo Scanno","url":"https:\/\/balzoscanno.com\/","logo":{"@type":"ImageObject","inLanguage":"en-GB","@id":"https:\/\/balzoscanno.com\/#\/schema\/logo\/image\/","url":"https:\/\/balzoscanno.com\/wp-content\/uploads\/2026\/03\/Balzo.png","contentUrl":"https:\/\/balzoscanno.com\/wp-content\/uploads\/2026\/03\/Balzo.png","width":1601,"height":496,"caption":"Balzo Scanno"},"image":{"@id":"https:\/\/balzoscanno.com\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/profile.php?id=61572664227109","https:\/\/www.instagram.com\/balzo_scanno\/","https:\/\/www.tiktok.com\/@balzo_scanno"]}]}},"_links":{"self":[{"href":"https:\/\/balzoscanno.com\/en\/wp-json\/wp\/v2\/sentieri\/1398","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/balzoscanno.com\/en\/wp-json\/wp\/v2\/sentieri"}],"about":[{"href":"https:\/\/balzoscanno.com\/en\/wp-json\/wp\/v2\/types\/sentieri"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/balzoscanno.com\/en\/wp-json\/wp\/v2\/media\/1399"}],"wp:attachment":[{"href":"https:\/\/balzoscanno.com\/en\/wp-json\/wp\/v2\/media?parent=1398"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}