{"id":28,"count":3,"description":"","link":"https:\/\/balzoscanno.com\/en\/product-category\/shop\/","name":"Shop","slug":"shop","taxonomy":"product_cat","parent":0,"meta":[],"menu_order":0,"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Shop Archivi - Balzo Scanno<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/balzoscanno.com\/en\/product-category\/shop\/\" \/>\n<meta property=\"og:locale\" content=\"en_GB\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Shop Archivi - Balzo Scanno\" \/>\n<meta property=\"og:url\" content=\"https:\/\/balzoscanno.com\/en\/product-category\/shop\/\" \/>\n<meta property=\"og:site_name\" content=\"Balzo Scanno\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"CollectionPage\",\"@id\":\"https:\\\/\\\/balzoscanno.com\\\/categoria-prodotto\\\/shop\\\/\",\"url\":\"https:\\\/\\\/balzoscanno.com\\\/categoria-prodotto\\\/shop\\\/\",\"name\":\"Shop Archivi - Balzo Scanno\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/balzoscanno.com\\\/#website\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/balzoscanno.com\\\/categoria-prodotto\\\/shop\\\/#breadcrumb\"},\"inLanguage\":\"en-GB\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/balzoscanno.com\\\/categoria-prodotto\\\/shop\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/balzoscanno.com\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Shop\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/balzoscanno.com\\\/#website\",\"url\":\"https:\\\/\\\/balzoscanno.com\\\/\",\"name\":\"Balzo Scanno\",\"description\":\"Balzo \u00e8 un progetto nato per rendere il territorio di Scanno pi\u00f9 accessibile a cittadini e turisti, fornendo informazioni e strumenti per viverlo al meglio.\",\"publisher\":{\"@id\":\"https:\\\/\\\/balzoscanno.com\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/balzoscanno.com\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-GB\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/balzoscanno.com\\\/#organization\",\"name\":\"Balzo Scanno\",\"url\":\"https:\\\/\\\/balzoscanno.com\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-GB\",\"@id\":\"https:\\\/\\\/balzoscanno.com\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/balzoscanno.com\\\/wp-content\\\/uploads\\\/2026\\\/03\\\/Balzo.png\",\"contentUrl\":\"https:\\\/\\\/balzoscanno.com\\\/wp-content\\\/uploads\\\/2026\\\/03\\\/Balzo.png\",\"width\":1601,\"height\":496,\"caption\":\"Balzo Scanno\"},\"image\":{\"@id\":\"https:\\\/\\\/balzoscanno.com\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/profile.php?id=61572664227109\",\"https:\\\/\\\/www.instagram.com\\\/balzo_scanno\\\/\",\"https:\\\/\\\/www.tiktok.com\\\/@balzo_scanno\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Shop Archivi - Balzo Scanno","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/balzoscanno.com\/en\/product-category\/shop\/","og_locale":"en_GB","og_type":"article","og_title":"Shop Archivi - Balzo Scanno","og_url":"https:\/\/balzoscanno.com\/en\/product-category\/shop\/","og_site_name":"Balzo Scanno","twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"CollectionPage","@id":"https:\/\/balzoscanno.com\/categoria-prodotto\/shop\/","url":"https:\/\/balzoscanno.com\/categoria-prodotto\/shop\/","name":"Shop Archivi - Balzo Scanno","isPartOf":{"@id":"https:\/\/balzoscanno.com\/#website"},"breadcrumb":{"@id":"https:\/\/balzoscanno.com\/categoria-prodotto\/shop\/#breadcrumb"},"inLanguage":"en-GB"},{"@type":"BreadcrumbList","@id":"https:\/\/balzoscanno.com\/categoria-prodotto\/shop\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/balzoscanno.com\/"},{"@type":"ListItem","position":2,"name":"Shop"}]},{"@type":"WebSite","@id":"https:\/\/balzoscanno.com\/#website","url":"https:\/\/balzoscanno.com\/","name":"Balzo Scanno","description":"Balzo \u00e8 un progetto nato per rendere il territorio di Scanno pi\u00f9 accessibile a cittadini e turisti, fornendo informazioni e strumenti per viverlo al meglio.","publisher":{"@id":"https:\/\/balzoscanno.com\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/balzoscanno.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-GB"},{"@type":"Organization","@id":"https:\/\/balzoscanno.com\/#organization","name":"Balzo Scanno","url":"https:\/\/balzoscanno.com\/","logo":{"@type":"ImageObject","inLanguage":"en-GB","@id":"https:\/\/balzoscanno.com\/#\/schema\/logo\/image\/","url":"https:\/\/balzoscanno.com\/wp-content\/uploads\/2026\/03\/Balzo.png","contentUrl":"https:\/\/balzoscanno.com\/wp-content\/uploads\/2026\/03\/Balzo.png","width":1601,"height":496,"caption":"Balzo Scanno"},"image":{"@id":"https:\/\/balzoscanno.com\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/profile.php?id=61572664227109","https:\/\/www.instagram.com\/balzo_scanno\/","https:\/\/www.tiktok.com\/@balzo_scanno"]}]}},"_links":{"self":[{"href":"https:\/\/balzoscanno.com\/en\/wp-json\/wp\/v2\/product_cat\/28","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/balzoscanno.com\/en\/wp-json\/wp\/v2\/product_cat"}],"about":[{"href":"https:\/\/balzoscanno.com\/en\/wp-json\/wp\/v2\/taxonomies\/product_cat"}],"wp:post_type":[{"href":"https:\/\/balzoscanno.com\/en\/wp-json\/wp\/v2\/product?product_cat=28"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}